{"id":54,"date":"2005-12-04T23:44:38","date_gmt":"2005-12-04T22:44:38","guid":{"rendered":"http:\/\/www.simpod.org\/blog\/acquario\/"},"modified":"2005-12-06T01:15:32","modified_gmt":"2005-12-06T00:15:32","slug":"acquario","status":"publish","type":"page","link":"http:\/\/www.simpod.org\/blog\/acquario\/","title":{"rendered":"Acquario"},"content":{"rendered":"<p><a href=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/acquario_2005_12_04.jpg\"><img decoding=\"async\" src=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/acquario_2005_12_04_small.jpg\" class=\"centered\" alt=\"Acquario 4 dicembre 2005\" \/><\/a><br \/>\nQuesto qua sopra \u00c3\u00a8 il mio acquario (foto fatta il 4 dicembre 2005). Cliccaci sopra per vedere la foto con maggiore dettaglio.<br \/>\nE&#8217; un acquario dolce da 90 litri avviato ormai da tre anni. Dopo i primi mesi di entusiasmo l&#8217;ho molto trascurato, e solo ultimamente mi \u00c3\u00a8 ripresa la passione. Con le dovute cure si \u00c3\u00a8 trasformato da un mostruoso ammasso di alghe abitato solo da tre poveri pesciolini (le petitelle, che ancora sopravvivono), a quello che \u00c3\u00a8 adesso.<br \/>\nClicca sulle foto sotto per vedere alcuni dettagli:<\/p>\n<div align=\"center\">\n<a href=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/botia.jpg\"><img decoding=\"async\" src=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/botia_small.jpg\" alt=\"Botia\" title=\"Botia\" \/><\/a> <a href=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/labeo.jpg\"><img decoding=\"async\" src=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/labeo_small.jpg\" alt=\"Labeo\" title=\"Labeo\"\/><\/a> <a href=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/coppia_di_labeo.jpg\"><img decoding=\"async\" src=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/coppia_di_labeo_small.jpg\" alt=\"Coppia di Labeo\" title=\"Coppia di Labeo\" \/><\/a><br \/>\n<a href=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/neon.jpg\"><img decoding=\"async\" src=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/neon_small.jpg\" alt=\"Branco di Neon\" title=\"Branco di Neon\" \/><\/a> <a href=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/otocinclus.jpg\"><img decoding=\"async\" src=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/otocinclus_small.jpg\" alt=\"Otocinclus\" title=\"Otocinclus\" \/><\/a> <a href=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/petitelle_e_otocinclus.jpg\"><img decoding=\"async\" src=\"http:\/\/www.simpod.org\/blog\/files\/acquario\/petitelle_e_otocinclus_small.jpg\" alt=\"Petitelle e Otocinclus\" title=\"Petitelle e Otocinclus\" \/><\/a>\n<\/div>\n<p>I pesci attualmente presenti nella vasca sono:<\/p>\n<ul>\n<li>18 Paracheirodon innesi (Neon)<\/li>\n<li>6 Otocinclus Affinis<\/li>\n<li>3 Hemigrammus bleheri (Petitella)<\/li>\n<li>2 Botia macracanthus<\/li>\n<li>2 Epalzeorhynchus Siamensis (Labeo rigato)<\/li>\n<\/ul>\n<p>Queste sono le piante:<\/p>\n<ul>\n<li>Hydrocotyle sibthorpioides<\/li>\n<li>Cyperus helferi<\/li>\n<li>Alternanthera rosaefolia<\/li>\n<li>Mayaca fluviatilis<\/li>\n<li>Bacopa caroliniana<\/li>\n<li>Nymphaea zenkeri<\/li>\n<li>Echinodorus ozelot<\/li>\n<li>Eleocharis acicularis<\/li>\n<li>Mayaca vandellii<\/li>\n<li>Lemna minor<\/li>\n<\/ul>\n<p>Attualmente i valori dell&#8217;acqua sono:<\/p>\n<ul>\n<li>Temperatura: 26 \u00c2\u00b0C<\/li>\n<li>pH: 7.2<\/li>\n<li>KH: 12.5\u00c2\u00b0<\/li>\n<li>GH: 11\u00c2\u00b0<\/li>\n<li>NH<font size=\"0.5\">4<\/font>: 0 mg\/l<\/li>\n<li>NO<font size=\"0.5\">2<\/font>: 0 mg\/l<\/li>\n<li>NO<font size=\"0.5\">3<\/font>: 5 mg\/l<\/li>\n<li>PO<font size=\"0.5\">4<\/font>: 0.02 mg\/l<\/li>\n<li>Fe: 0.03 mg\/l<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Questo qua sopra \u00c3\u00a8 il mio acquario (foto fatta il 4 dicembre 2005). Cliccaci sopra per vedere la foto con maggiore dettaglio. E&#8217; un acquario dolce da 90 litri avviato ormai da tre anni. Dopo i primi mesi di entusiasmo l&#8217;ho molto trascurato, e solo ultimamente mi \u00c3\u00a8 ripresa la passione. Con le dovute cure [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-54","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.simpod.org\/blog\/wp-json\/wp\/v2\/pages\/54","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.simpod.org\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.simpod.org\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.simpod.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.simpod.org\/blog\/wp-json\/wp\/v2\/comments?post=54"}],"version-history":[{"count":0,"href":"http:\/\/www.simpod.org\/blog\/wp-json\/wp\/v2\/pages\/54\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.simpod.org\/blog\/wp-json\/wp\/v2\/media?parent=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}